{"id":20348,"date":"2024-04-22T19:30:35","date_gmt":"2024-04-23T02:30:35","guid":{"rendered":"https:\/\/rentasmaza.com\/?p=20348"},"modified":"2024-04-22T20:01:56","modified_gmt":"2024-04-23T03:01:56","slug":"semana-internacional-de-la-moto-mazatlan-2024","status":"publish","type":"post","link":"https:\/\/rentasmaza.com\/index.php\/2024\/04\/22\/semana-internacional-de-la-moto-mazatlan-2024\/","title":{"rendered":"Semana Internacional de la Moto Mazatl\u00e1n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20348\" class=\"elementor elementor-20348\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e2ed2e e-flex e-con-boxed e-con e-parent\" data-id=\"5e2ed2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd13bd3 elementor-widget elementor-widget-text-editor\" data-id=\"bd13bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Semana Internacional de la Moto en Mazatl\u00e1n, M\u00e9xico, es un evento emocionante que re\u00fane a apasionados de las motocicletas de todo el mundo para celebrar la cultura y la pasi\u00f3n por el motociclismo. Con una agenda llena de actividades emocionantes, desde desfiles de motos personalizadas hasta competiciones de habilidades, el evento promete una experiencia inolvidable para todos los participantes. Adem\u00e1s, los visitantes tendr\u00e1n la oportunidad de explorar la impresionante ciudad costera de Mazatl\u00e1n, con sus playas de arena dorada, deliciosa gastronom\u00eda y una atm\u00f3sfera vibrante que complementa perfectamente la energ\u00eda del evento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b3c16a e-flex e-con-boxed e-con e-parent\" data-id=\"8b3c16a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f545db elementor-widget elementor-widget-text-editor\" data-id=\"2f545db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Desfiles, competiciones, conciertos y m\u00e1s&#8230;<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac64fe1 e-flex e-con-boxed e-con e-parent\" data-id=\"ac64fe1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14ea5c3 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"14ea5c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de Im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/semana-de-la-moto-2023-400x242.jpeg\" alt=\"semana-de-la-moto-2023\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/semana-de-la-moto-2-400x242.jpg\" alt=\"semana-de-la-moto-2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/Desfile-Semana-de-la-Moto-Mazatlan-2016-3-a-400x242.jpg\" alt=\"Desfile-Semana-de-la-Moto-Mazatl\u00e1n-2016-3-a\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/semana-de-la-moto-3-400x242.jpg\" alt=\"semana-de-la-moto-3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/sm-moto-mazatlan-15-400x242.jpg\" alt=\"sm-moto-mazatlan-15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/F6_769-400x242.jpg\" alt=\"F6_769\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38eb84ca e-flex e-con-boxed e-con e-parent\" data-id=\"38eb84ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d6c4cf6 elementor-widget elementor-widget-text-editor\" data-id=\"4d6c4cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p>Este a\u00f1o, la Semana Internacional de la Moto promete superar todas las expectativas, con una agenda a\u00fan m\u00e1s diversa y emocionante. Desde conciertos en vivo hasta exposiciones de fabricantes de motocicletas, habr\u00e1 algo para todos los amantes de las dos ruedas. Adem\u00e1s, los participantes tendr\u00e1n la oportunidad de conectar con otros entusiastas, compartiendo historias y experiencias mientras celebran su pasi\u00f3n compartida por el motociclismo. Con tantas actividades emocionantes y una atm\u00f3sfera electrizante, la Semana Internacional de la Moto en Mazatl\u00e1n promete ser un evento destacado en el calendario de eventos de 2024 para todos los apasionados de las motos.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d7883d e-flex e-con-boxed e-con e-parent\" data-id=\"4d7883d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a30f058 elementor-widget elementor-widget-google_maps\" data-id=\"a30f058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=centro%20de%20convenciones%20mazatlan&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"centro de convenciones mazatlan\"\n\t\t\t\t\taria-label=\"centro de convenciones mazatlan\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-acb2bdd e-flex e-con-boxed e-con e-parent\" data-id=\"acb2bdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43ccf75 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"43ccf75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c21bce e-flex e-con-boxed e-con e-parent\" data-id=\"8c21bce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-670e506 elementor-widget__width-auto elementor-widget elementor-widget-WpRentals_Video_Player\" data-id=\"670e506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"WpRentals_Video_Player.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wprentals_video_wrapper\"><a href=\"https:\/\/www.youtube.com\/embed\/OgVoI8fpRUc?wmode=transparent&#038;rel=0\"  data-autoplay=\"true\" data-vbtype=\"video\" class=\"venobox\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-play-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M371.7 238l-176-107c-15.8-8.8-35.7 2.5-35.7 21v208c0 18.4 19.8 29.8 35.7 21l176-101c16.4-9.1 16.4-32.8 0-42zM504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256z\"><\/path><\/svg><\/a><\/div>\n    <script type=\"text\/javascript\">\n        \/\/<![CDATA[\n        jQuery(document).ready(function(){\n            if (jQuery(\".venobox\").length > 0){\n                jQuery(\".venobox\").venobox({   \n                });\n            }\n        });\n        \/\/]]>\n    <\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Semana Internacional de la Moto en Mazatl\u00e1n, M\u00e9xico, es un evento emocionante que re\u00fane a apasionados de las motocicletas de todo el mundo para celebrar la cultura y la pasi\u00f3n por el motociclismo. Con una agenda llena de actividades emocionantes, desde desfiles de motos personalizadas hasta competiciones de habilidades, el evento promete una experiencia &#8230;<\/p>\n","protected":false},"author":7,"featured_media":20351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"iawp_total_views":3,"footnotes":""},"categories":[182,181],"tags":[],"class_list":["post-20348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-diversion"],"jetpack_featured_media_url":"https:\/\/rentasmaza.com\/wp-content\/uploads\/2024\/04\/semana-de-la-moto-2023.jpeg","_links":{"self":[{"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/posts\/20348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/comments?post=20348"}],"version-history":[{"count":29,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/posts\/20348\/revisions"}],"predecessor-version":[{"id":20387,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/posts\/20348\/revisions\/20387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/media\/20351"}],"wp:attachment":[{"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/media?parent=20348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/categories?post=20348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rentasmaza.com\/index.php\/wp-json\/wp\/v2\/tags?post=20348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}